{"id":15604,"date":"2024-10-30T10:58:13","date_gmt":"2024-10-30T09:58:13","guid":{"rendered":"https:\/\/www.schreiber-weinert.de\/?p=15604"},"modified":"2024-11-04T14:08:56","modified_gmt":"2024-11-04T13:08:56","slug":"bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische","status":"publish","type":"post","link":"https:\/\/www.schreiber-weinert.de\/en\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/","title":{"rendered":"(Deutsch) Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.schreiber-weinert.de\/de\/wp-json\/wp\/v2\/posts\/15604\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":15605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>(Deutsch) Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische - schreiber-weinert.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Deutsch) Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische - schreiber-weinert.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/\" \/>\n<meta property=\"og:site_name\" content=\"schreiber-weinert.de\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-30T09:58:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-04T13:08:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schreiber-weinert.de\/wp-content\/uploads\/2024\/10\/NEWSROOM-Backboon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"866\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lukas Perkovic\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lukas Perkovic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/\",\"url\":\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/\",\"name\":\"(Deutsch) Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische - schreiber-weinert.de\",\"isPartOf\":{\"@id\":\"https:\/\/www.schreiber-weinert.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.schreiber-weinert.de\/wp-content\/uploads\/2024\/10\/NEWSROOM-Backboon.png\",\"datePublished\":\"2024-10-30T09:58:13+00:00\",\"dateModified\":\"2024-11-04T13:08:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.schreiber-weinert.de\/#\/schema\/person\/28711109e3885bd105ae069dbe2498f9\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#primaryimage\",\"url\":\"https:\/\/www.schreiber-weinert.de\/wp-content\/uploads\/2024\/10\/NEWSROOM-Backboon.png\",\"contentUrl\":\"https:\/\/www.schreiber-weinert.de\/wp-content\/uploads\/2024\/10\/NEWSROOM-Backboon.png\",\"width\":1200,\"height\":866},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.schreiber-weinert.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.schreiber-weinert.de\/#website\",\"url\":\"https:\/\/www.schreiber-weinert.de\/\",\"name\":\"schreiber-weinert.de\",\"description\":\"Schreiber + Weinert GmbH\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.schreiber-weinert.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.schreiber-weinert.de\/#\/schema\/person\/28711109e3885bd105ae069dbe2498f9\",\"name\":\"Lukas Perkovic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.schreiber-weinert.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/848bab57940a0fc775ff630ca6906ef195bd35b612ef15e4e03ab18a2e001495?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/848bab57940a0fc775ff630ca6906ef195bd35b612ef15e4e03ab18a2e001495?s=96&d=mm&r=g\",\"caption\":\"Lukas Perkovic\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(Deutsch) Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische - schreiber-weinert.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/","og_locale":"en_US","og_type":"article","og_title":"(Deutsch) Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische - schreiber-weinert.de","og_url":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/","og_site_name":"schreiber-weinert.de","article_published_time":"2024-10-30T09:58:13+00:00","article_modified_time":"2024-11-04T13:08:56+00:00","og_image":[{"width":1200,"height":866,"url":"https:\/\/www.schreiber-weinert.de\/wp-content\/uploads\/2024\/10\/NEWSROOM-Backboon.png","type":"image\/png"}],"author":"Lukas Perkovic","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Lukas Perkovic","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/","url":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/","name":"(Deutsch) Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische - schreiber-weinert.de","isPartOf":{"@id":"https:\/\/www.schreiber-weinert.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#primaryimage"},"image":{"@id":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schreiber-weinert.de\/wp-content\/uploads\/2024\/10\/NEWSROOM-Backboon.png","datePublished":"2024-10-30T09:58:13+00:00","dateModified":"2024-11-04T13:08:56+00:00","author":{"@id":"https:\/\/www.schreiber-weinert.de\/#\/schema\/person\/28711109e3885bd105ae069dbe2498f9"},"breadcrumb":{"@id":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#primaryimage","url":"https:\/\/www.schreiber-weinert.de\/wp-content\/uploads\/2024\/10\/NEWSROOM-Backboon.png","contentUrl":"https:\/\/www.schreiber-weinert.de\/wp-content\/uploads\/2024\/10\/NEWSROOM-Backboon.png","width":1200,"height":866},{"@type":"BreadcrumbList","@id":"https:\/\/www.schreiber-weinert.de\/bekannt-aus-hoehle-der-loewen-ergonomisches-stehacessoire-backboon-fuer-schreibtische\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.schreiber-weinert.de\/"},{"@type":"ListItem","position":2,"name":"Bekannt aus H\u00f6hle der L\u00f6wen: Ergonomisches Steh-Accessoire Backboon f\u00fcr Schreibtische"}]},{"@type":"WebSite","@id":"https:\/\/www.schreiber-weinert.de\/#website","url":"https:\/\/www.schreiber-weinert.de\/","name":"schreiber-weinert.de","description":"Schreiber + Weinert GmbH","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schreiber-weinert.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.schreiber-weinert.de\/#\/schema\/person\/28711109e3885bd105ae069dbe2498f9","name":"Lukas Perkovic","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.schreiber-weinert.de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/848bab57940a0fc775ff630ca6906ef195bd35b612ef15e4e03ab18a2e001495?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/848bab57940a0fc775ff630ca6906ef195bd35b612ef15e4e03ab18a2e001495?s=96&d=mm&r=g","caption":"Lukas Perkovic"}}]}},"_links":{"self":[{"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/posts\/15604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/comments?post=15604"}],"version-history":[{"count":1,"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/posts\/15604\/revisions"}],"predecessor-version":[{"id":15606,"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/posts\/15604\/revisions\/15606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/media\/15605"}],"wp:attachment":[{"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/media?parent=15604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/categories?post=15604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schreiber-weinert.de\/en\/wp-json\/wp\/v2\/tags?post=15604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}